{"id":1977,"date":"2022-04-04T13:00:57","date_gmt":"2022-04-04T16:00:57","guid":{"rendered":"http:\/\/www.profiautos.com.br\/novosite\/?post_type=product&#038;p=1977"},"modified":"2026-06-19T17:17:12","modified_gmt":"2026-06-19T20:17:12","slug":"mecanica-basica-de-bicicletas-para-amadores","status":"publish","type":"product","link":"https:\/\/www.profiautos.com.br\/novosite\/produto\/mecanica-basica-de-bicicletas-para-amadores\/","title":{"rendered":"MEC\u00c2NICA DE BICICLETAS"},"content":{"rendered":"<p><strong>MEC\u00c2NICA DE BICICLETAS\u00a0<\/strong><\/p>\n<p><strong>Objetivo:<\/strong> Capacitar ciclistas e entusiastas a realizar os principais servi\u00e7os de manuten\u00e7\u00e3o preventiva e corretiva em bicicletas, desenvolvendo conhecimentos b\u00e1sicos sobre regulagem, ajustes, identifica\u00e7\u00e3o de defeitose conserva\u00e7\u00e3o dos componentes, proporcionando mais seguran\u00e7a, autonomia e melhor desempenho durante o uso da bicicleta.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>CONTE\u00daDO PROGRAM\u00c1TICO:<\/strong><\/p>\n<ul>\n<li>Conhecendo os componentes e especifica\u00e7\u00f5es de uma bicicleta;<\/li>\n<li>Ferramentas espec\u00edficas para mec\u00e2nica de bike;<\/li>\n<li>Reparo de c\u00e2mera de ar e pneus;<\/li>\n<li>Diagn\u00f3stico de manuten\u00e7\u00e3o em pe\u00e7as (coroa e catraca)<\/li>\n<li>Limpeza e lubrifica\u00e7\u00e3o do kit de trasnmiss\u00e3o;<\/li>\n<li>Procedimentos de seguran\u00e7a e kit de reparo para pedalar nas ruas ou trilhas;<\/li>\n<li>Toda a revis\u00e3o na pr\u00e1tica.<\/li>\n<\/ul>\n<p><strong>Dura\u00e7\u00e3o: 1<\/strong> semana (10 hrs);<\/p>\n<p><strong>Hor\u00e1rio das aulas:<\/strong> Segunda-feira a Quinta-feira (19:00 \u00e1s 21:30);<\/p>\n<p><strong>Per\u00edodo:<\/strong> 13\/07\/2026 (previs\u00e3o)<\/p>\n<p><strong>Incluso:<\/strong> Material Did\u00e1tico e Certificado de Participa\u00e7\u00e3o;<\/p>\n<p><strong>Forma de Pagamento:<\/strong> A vista ou 4x no cart\u00e3o de cr\u00e9dito.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MEC\u00c2NICA DE BICICLETAS\u00a0 Objetivo: Capacitar ciclistas e entusiastas a realizar os principais servi\u00e7os de manuten\u00e7\u00e3o preventiva e corretiva em bicicletas, desenvolvendo conhecimentos b\u00e1sicos sobre regulagem, ajustes, identifica\u00e7\u00e3o de defeitose conserva\u00e7\u00e3o dos componentes, proporcionando mais seguran\u00e7a, autonomia e melhor desempenho durante o uso da bicicleta. &nbsp; CONTE\u00daDO PROGRAM\u00c1TICO: Conhecendo os componentes e especifica\u00e7\u00f5es de uma bicicleta; [&hellip;]<\/p>\n","protected":false},"featured_media":3879,"template":"","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0},"product_cat":[14,10],"product_tag":[],"class_list":{"0":"post-1977","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-cursos-com-matriculas-abertas","7":"product_cat-cursos-de-motocicletas","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/www.profiautos.com.br\/novosite\/wp-json\/wp\/v2\/product\/1977"}],"collection":[{"href":"https:\/\/www.profiautos.com.br\/novosite\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.profiautos.com.br\/novosite\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.profiautos.com.br\/novosite\/wp-json\/wp\/v2\/media\/3879"}],"wp:attachment":[{"href":"https:\/\/www.profiautos.com.br\/novosite\/wp-json\/wp\/v2\/media?parent=1977"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.profiautos.com.br\/novosite\/wp-json\/wp\/v2\/product_cat?post=1977"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.profiautos.com.br\/novosite\/wp-json\/wp\/v2\/product_tag?post=1977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}